{"id":196,"date":"2024-11-27T09:23:58","date_gmt":"2024-11-27T08:23:58","guid":{"rendered":"https:\/\/riverspc.com\/blog\/?p=196"},"modified":"2025-11-04T09:30:25","modified_gmt":"2025-11-04T08:30:25","slug":"von-einer-luxuswohnung-zu-einem-industriepark","status":"publish","type":"post","link":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/","title":{"rendered":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"196\" class=\"elementor elementor-196\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08910f6 e-con-full e-flex e-con e-parent\" data-id=\"08910f6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-094cebc elementor-widget elementor-widget-text-editor\" data-id=\"094cebc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Wie vielf\u00e4ltig und unbest\u00e4ndig der Immobilienmarkt ist, zeigt die Geschichte unseres j\u00fcngsten Projekts, das mit einer Luxuswohnung am Plattensee begann und in zwei Industriepark-Auftr\u00e4gen gipfelte. Als Ergebnis unserer Zusammenarbeit mit EBH sind die Miniparks von \u00dcll\u0151 und Szentendre unsere j\u00fcngsten Schwerpunkte. Wir freuen uns darauf, diese ehrgeizigen Projekte in Angriff zu nehmen.<\/h6><h5>Vom Wohn- zum Industriegebiet: Unser Weg<\/h5><h6>Als wir den Auftrag erhielten, eine Luxuswohnung am Plattensee zu verkaufen, ahnten wir nicht, dass uns diese Zusammenarbeit in eine v\u00f6llig neue Richtung f\u00fchren w\u00fcrde. Das Projekt brachte uns n\u00e4her an EBH heran, die sich auch auf industrielle Entwicklungsprojekte konzentrieren.<\/h6><h6>Nach Verhandlungen unterzeichneten wir einen Vertrag zur Beteiligung an Projekten in zwei Industrieparks &#8211; \u00dcll\u0151 und Szentendre.<\/h6><h5>Industriepark \u00dcll\u0151: ein wichtiger Standort<\/h5><h6>Das erste Projekt befindet sich in \u00dcll\u0151, im \u00f6stlichen Ballungsraum von Budapest. Dieses 6,7 Hektar gro\u00dfe Entwicklungsgebiet ist \u00e4u\u00dferst vielversprechend, da es aufgrund seiner N\u00e4he zu den Autobahnen M0\/M4, der Hauptverkehrsstra\u00dfe 4 und dem internationalen Flughafen Liszt Ferenc einen hervorragenden Standort f\u00fcr Unternehmen darstellt. Sein logistisches Potenzial ist perfekt, da sowohl der Stra\u00dfen- als auch der Luftverkehr von hier aus leicht zug\u00e4nglich sind.<\/h6><h6>Ein gro\u00dfer Vorteil des Industrieparks ist seine hervorragende Infrastruktur. Das Gebiet eignet sich nicht nur f\u00fcr gro\u00dfe Unternehmen, sondern auch f\u00fcr kleinere Firmen, da es flexibel gestaltet ist und \u00fcber ein breites Spektrum an Einrichtungen verf\u00fcgt.<\/h6><h5>Industriepark Szentendre: M\u00f6glichkeiten in einer historischen Stadt<\/h5><h6>Das zweite Projekt befindet sich im malerischen Szentendre, wo ein alteingesessenes Industriegebiet auf neue Entwicklungen wartet. Das 6,7 Hektar gro\u00dfe Gel\u00e4nde befindet sich im westlichen Ballungsraum von Budapest, innerhalb der Verwaltungsgrenzen von Szentendre. Die ausgezeichnete Verkehrsanbindung macht es zu einem sehr attraktiven Standort f\u00fcr Industrieunternehmen. Die Autobahnen M0\/M2 und M3 sind \u00fcber den nahe gelegenen Knotenpunkt Budakalaz und die Megyeri-Br\u00fccke leicht zu erreichen.<\/h6><h6>Dieser Standort k\u00f6nnte sich sowohl f\u00fcr Produktions- als auch f\u00fcr Dienstleistungsunternehmen anbieten, da sowohl die Infrastruktur als auch die Verkehrsanbindung das Unternehmenswachstum unterst\u00fctzen. Szentendre ist f\u00fcr sein kulturelles und k\u00fcnstlerisches Erbe bekannt, verf\u00fcgt aber auch \u00fcber ein gro\u00dfes industrielles Potenzial, was die wirtschaftliche Attraktivit\u00e4t der Stadt weiter steigert.<\/h6><h5>Was bedeutet diese Chance f\u00fcr uns?<\/h5><h6>Diese Projekte sind nicht nur ein Symbol f\u00fcr unsere berufliche Entwicklung, sondern auch eine gro\u00dfe Motivation f\u00fcr uns. Die Entwicklung der Industrieparks in \u00dcll\u0151 und Szentendre gibt uns die M\u00f6glichkeit, unser professionelles Portfolio weiter auszubauen und unseren Partnern noch innovativere L\u00f6sungen anzubieten. Die Nachfrage nach Industrieimmobilien steigt und diese Projekte folgen diesem Trend.<\/h6><h6>Wenn Sie auf der Suche nach einem Immobilienverkauf oder einer Beratung sind, kontaktieren Sie uns! Wir helfen Ihnen gerne bei allen Fragen und sorgen daf\u00fcr, dass Ihre Projekte in den besten H\u00e4nden sind!<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wie vielf\u00e4ltig und unbest\u00e4ndig der Immobilienmarkt ist, zeigt die Geschichte unseres j\u00fcngsten Projekts, das mit einer Luxuswohnung am Plattensee begann und in zwei Industriepark-Auftr\u00e4gen gipfelte. Als Ergebnis unserer Zusammenarbeit mit EBH sind die Miniparks von \u00dcll\u0151 und Szentendre unsere j\u00fcngsten Schwerpunkte. Wir freuen uns darauf, diese ehrgeizigen Projekte in Angriff zu nehmen. Vom Wohn- zum [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-egyeb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog<\/title>\n<meta name=\"description\" content=\"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog\" \/>\n<meta property=\"og:description\" content=\"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\" \/>\n<meta property=\"og:site_name\" content=\"Riverspc Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T08:23:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T08:30:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"RPC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" \/>\n\t<meta name=\"twitter:data1\" content=\"RPC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 perc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\"},\"author\":{\"name\":\"RPC\",\"@id\":\"https:\/\/riverspc.com\/blog\/#\/schema\/person\/d62907cde6213ceb07a8d2e704b75813\"},\"headline\":\"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen?\",\"datePublished\":\"2024-11-27T08:23:58+00:00\",\"dateModified\":\"2025-11-04T08:30:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\"},\"wordCount\":488,\"publisher\":{\"@id\":\"https:\/\/riverspc.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png\",\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\",\"url\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\",\"name\":\"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog\",\"isPartOf\":{\"@id\":\"https:\/\/riverspc.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png\",\"datePublished\":\"2024-11-27T08:23:58+00:00\",\"dateModified\":\"2025-11-04T08:30:25+00:00\",\"description\":\"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.\",\"breadcrumb\":{\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage\",\"url\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png\",\"contentUrl\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\/\/riverspc.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/riverspc.com\/blog\/#website\",\"url\":\"https:\/\/riverspc.com\/blog\/\",\"name\":\"Riverspc Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/riverspc.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/riverspc.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/riverspc.com\/blog\/#organization\",\"name\":\"Riverspc Blog\",\"url\":\"https:\/\/riverspc.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/riverspc.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-rpc__logo.png\",\"contentUrl\":\"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-rpc__logo.png\",\"width\":160,\"height\":182,\"caption\":\"Riverspc Blog\"},\"image\":{\"@id\":\"https:\/\/riverspc.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/riverspc.com\/blog\/#\/schema\/person\/d62907cde6213ceb07a8d2e704b75813\",\"name\":\"RPC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/riverspc.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/470a8aaf0a691e5918b89da4b461e290f3e9d957ab4e6f4497e492d665db0e02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/470a8aaf0a691e5918b89da4b461e290f3e9d957ab4e6f4497e492d665db0e02?s=96&d=mm&r=g\",\"caption\":\"RPC\"},\"url\":\"https:\/\/riverspc.com\/blog\/author\/viktoria\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog","description":"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/","og_locale":"hu_HU","og_type":"article","og_title":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog","og_description":"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.","og_url":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/","og_site_name":"Riverspc Blog","article_published_time":"2024-11-27T08:23:58+00:00","article_modified_time":"2025-11-04T08:30:25+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-1024x683.png","type":"image\/png"}],"author":"RPC","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"RPC","Becs\u00fclt olvas\u00e1si id\u0151":"3 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#article","isPartOf":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/"},"author":{"name":"RPC","@id":"https:\/\/riverspc.com\/blog\/#\/schema\/person\/d62907cde6213ceb07a8d2e704b75813"},"headline":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen?","datePublished":"2024-11-27T08:23:58+00:00","dateModified":"2025-11-04T08:30:25+00:00","mainEntityOfPage":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/"},"wordCount":488,"publisher":{"@id":"https:\/\/riverspc.com\/blog\/#organization"},"image":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage"},"thumbnailUrl":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png","inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/","url":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/","name":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen? - Riverspc Blog","isPartOf":{"@id":"https:\/\/riverspc.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage"},"image":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage"},"thumbnailUrl":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png","datePublished":"2024-11-27T08:23:58+00:00","dateModified":"2025-11-04T08:30:25+00:00","description":"Vom Luxusapartment zum Industriepark: zwei neue Auftr\u00e4ge in \u00dcll\u0151 und Szentendre \u2013 hervorragende Logistik, starke Infrastruktur.","breadcrumb":{"@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#primaryimage","url":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png","contentUrl":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/riverspc.com\/blog\/de\/2024\/11\/27\/von-einer-luxuswohnung-zu-einem-industriepark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/riverspc.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Von einer Luxuswohnung am Plattensee zu einem Industriepark: Wie haben wir zwei gro\u00dfe Industrieauftr\u00e4ge gewonnen?"}]},{"@type":"WebSite","@id":"https:\/\/riverspc.com\/blog\/#website","url":"https:\/\/riverspc.com\/blog\/","name":"Riverspc Blog","description":"","publisher":{"@id":"https:\/\/riverspc.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riverspc.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/riverspc.com\/blog\/#organization","name":"Riverspc Blog","url":"https:\/\/riverspc.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/riverspc.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-rpc__logo.png","contentUrl":"https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-rpc__logo.png","width":160,"height":182,"caption":"Riverspc Blog"},"image":{"@id":"https:\/\/riverspc.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/riverspc.com\/blog\/#\/schema\/person\/d62907cde6213ceb07a8d2e704b75813","name":"RPC","image":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/riverspc.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/470a8aaf0a691e5918b89da4b461e290f3e9d957ab4e6f4497e492d665db0e02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/470a8aaf0a691e5918b89da4b461e290f3e9d957ab4e6f4497e492d665db0e02?s=96&d=mm&r=g","caption":"RPC"},"url":"https:\/\/riverspc.com\/blog\/author\/viktoria\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png",2560,1707,false],"landscape":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png",2560,1707,false],"portraits":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4.png",2560,1707,false],"thumbnail":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-150x150.png",150,150,true],"medium":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-300x200.png",300,200,true],"large":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-1024x683.png",1024,683,true],"1536x1536":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-1536x1024.png",1536,1024,true],"2048x2048":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-2048x1366.png",2048,1366,true],"trp-custom-language-flag":["https:\/\/riverspc.com\/blog\/wp-content\/uploads\/2024\/11\/4-18x12.png",18,12,true]},"rttpg_author":{"display_name":"RPC","author_link":"https:\/\/riverspc.com\/blog\/author\/viktoria\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/riverspc.com\/blog\/de\/category\/egyeb\/\" rel=\"category tag\">Egy\u00e9b<\/a>","rttpg_excerpt":"Wie vielf\u00e4ltig und unbest\u00e4ndig der Immobilienmarkt ist, zeigt die Geschichte unseres j\u00fcngsten Projekts, das mit einer Luxuswohnung am Plattensee begann und in zwei Industriepark-Auftr\u00e4gen gipfelte. Als Ergebnis unserer Zusammenarbeit mit EBH sind die Miniparks von \u00dcll\u0151 und Szentendre unsere j\u00fcngsten Schwerpunkte. Wir freuen uns darauf, diese ehrgeizigen Projekte in Angriff zu nehmen. Vom Wohn- zum&hellip;","_links":{"self":[{"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/posts\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":3,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"predecessor-version":[{"id":199,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/posts\/196\/revisions\/199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/media\/382"}],"wp:attachment":[{"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riverspc.com\/blog\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}